{"id":2946,"date":"2024-02-12T13:32:49","date_gmt":"2024-02-12T11:32:49","guid":{"rendered":"https:\/\/hotel-excelsior.net\/urlaub-mit-haustier\/"},"modified":"2026-04-28T16:13:04","modified_gmt":"2026-04-28T13:13:04","slug":"urlaub-mit-haustier","status":"publish","type":"page","link":"https:\/\/hotel-excelsior.net\/de\/urlaub-mit-haustier\/","title":{"rendered":"Urlaub mit Haustier"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2946\" class=\"elementor elementor-2946 elementor-2914\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-709d6e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"709d6e1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-15e2a84\" data-id=\"15e2a84\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8495cbc elementor-widget elementor-widget-heading\" data-id=\"8495cbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Urlaub mit Haustier<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ab8597 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3ab8597\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27372ad\" data-id=\"27372ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c704722 elementor-widget elementor-widget-html\" data-id=\"c704722\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<!-- start Search form script -->\r\n<div id=\"block-search\">\r\n  <div id=\"be-search-form\" class=\"be-container\">\r\n    <a href=\"https:\/\/exely.bg\/\" rel=\"nofollow noopener\" target=\"_blank\">Hotel management software<\/a>\r\n  <\/div>\r\n<\/div>\r\n<!-- end Search form script -->\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-461d19a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"461d19a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1659d3a\" data-id=\"1659d3a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a8e2b1 elementor-widget elementor-widget-text-editor\" data-id=\"8a8e2b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li>Bis zu einem gut erzogenen Haustier (Katze oder Hund) pro Zimmer mit einem H\u00f6chstgewicht von <b>5 kg<\/b> ist im Hotel Excelsior willkommen.<\/li><li>Alle Haustiere m\u00fcssen beim Check-in an der Rezeption angemeldet werden. Wir bitten darum, dass Haustiere au\u00dferhalb des Zimmers an der Leine oder in einer geeigneten Kiste\/Tasche mitgef\u00fchrt werden.<\/li><li>F\u00fcr jeden Tag des Aufenthalts eines Haustiers wird eine Geb\u00fchr von 30 BGN Tag erhoben.<\/li><li>Haustiere m\u00fcssen vollst\u00e4ndig ausgebildet sein und von ihren Besitzern gut kontrolliert werden.<\/li><li>Haustiere k\u00f6nnen nur dann allein im Zimmer gelassen werden, wenn sie andere G\u00e4ste in der Anlage nicht st\u00f6ren. Bringen Sie die Kennzeichnung f\u00fcr Haustiere immer an der Au\u00dfenseite der T\u00fcr an, wenn sich das Haustier im Raum befindet. <\/li><li>Haustiere sind in den Pools, auf den Liegest\u00fchlen und im Restaurant nicht erlaubt.<\/li><li>Jeder Tierhalter ist daf\u00fcr verantwortlich, hinter seinem Tier aufzur\u00e4umen.<\/li><li>Jedes unruhige Verhalten, wie z. B. lautes Bellen, muss kontrolliert werden, um andere nicht zu bel\u00e4stigen.<\/li><li>Der Gast sollte sich mit der Rezeption in Verbindung setzen, um die Reinigung zu einem geeigneten Zeitpunkt zu vereinbaren.<\/li><li>Die G\u00e4ste haften f\u00fcr alle Sch\u00e4den, die durch ihr Haustier verursacht werden, und verpflichten sich, diese in vollem Umfang zu ersetzen.<br><br><\/li><\/ul><p><strong>Einrichtungen f\u00fcr G\u00e4ste mit Haustieren:<\/strong><\/p><ul><li>Eine pers\u00f6nliche Willkommenskarte des Hotelmanagers mit einer Liste der haustierfreundlichen Serviceleistungen in der Umgebung, einschlie\u00dflich Spazierwegen. Informationen \u00fcber Tierarztpraxen, Tierhandlungen und Hundesalons, Tierpensionen und Restaurants, die Haustiere akzeptieren.30<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Urlaub mit Haustier Hotel management software Bis zu einem gut erzogenen Haustier (Katze oder Hund) pro Zimmer mit einem H\u00f6chstgewicht von 5 kg ist im Hotel Excelsior willkommen. Alle Haustiere m\u00fcssen beim Check-in an der Rezeption angemeldet werden. Wir bitten darum, dass Haustiere au\u00dferhalb des Zimmers an der Leine oder in einer geeigneten Kiste\/Tasche mitgef\u00fchrt [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-2946","page","type-page","status-publish","hentry"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 03:15:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hotel-excelsior.net\/de\/wp-json\/wp\/v2\/pages\/2946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel-excelsior.net\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hotel-excelsior.net\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hotel-excelsior.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel-excelsior.net\/de\/wp-json\/wp\/v2\/comments?post=2946"}],"version-history":[{"count":0,"href":"https:\/\/hotel-excelsior.net\/de\/wp-json\/wp\/v2\/pages\/2946\/revisions"}],"wp:attachment":[{"href":"https:\/\/hotel-excelsior.net\/de\/wp-json\/wp\/v2\/media?parent=2946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}